{"id":11248,"date":"2023-10-06T19:35:28","date_gmt":"2023-10-06T17:35:28","guid":{"rendered":"https:\/\/hiros.be\/new-collaboration-with-stanley-ollivier\/"},"modified":"2023-10-06T19:39:34","modified_gmt":"2023-10-06T17:39:34","slug":"new-collaboration-with-stanley-ollivier","status":"publish","type":"post","link":"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/","title":{"rendered":"New collaboration with Stanley Ollivier!"},"content":{"rendered":"\n<p>06.10.2023 \u2013 Hiros is meer dan enthousiast om het nieuws te delen dat we een nieuwe samenwerking aangaan met Stanley Ollivier!<\/p>\n\n\n\n<p>Stanley is een danser, performer, maker, fysiek acteur &amp; DJ uit Parijs, Frankrijk. Hij volgde een opleiding bij AID (FR), bij CNSMDP (FR) en bij P.A.R.T.S, waar hij zijn Master of Arts in dans behaalde. Hij werkt rond vragen over de rol van amusement in hedendaagse dans, contextverschuiving, identiteit, humor, zorg en veelzijdigheid. Lees meer over Stanley en zijn werk op zijn gloednieuwe <a href=\"https:\/\/hiros.be\/nl\/artiesten\/stanley-ollivier\/\"><strong>artiestenpagina<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>06.10.2023 \u2013 Hiros is meer dan enthousiast om het nieuws te delen dat we een<\/p>\n","protected":false},"author":5,"featured_media":11244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[287],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>New collaboration with Stanley Ollivier! &ndash; Hiros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New collaboration with Stanley Ollivier! &ndash; Hiros\" \/>\n<meta property=\"og:description\" content=\"06.10.2023 \u2013 Hiros is meer dan enthousiast om het nieuws te delen dat we een\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/\" \/>\n<meta property=\"og:site_name\" content=\"Hiros\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-06T17:35:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-06T17:39:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hiros.be\/wp-content\/uploads\/2023\/10\/cropped-horizontal-DC_portrait-Ollivier-Stanley_high_46-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dagmar Teurelincx\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dagmar Teurelincx\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/\"},\"author\":{\"name\":\"Dagmar Teurelincx\",\"@id\":\"https:\/\/hiros.be\/en\/#\/schema\/person\/1d5315e21e564e12c8e0f36c0cd52ee4\"},\"headline\":\"New collaboration with Stanley Ollivier!\",\"datePublished\":\"2023-10-06T17:35:28+00:00\",\"dateModified\":\"2023-10-06T17:39:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\/\/hiros.be\/en\/#organization\"},\"articleSection\":[\"New collaboration\"],\"inLanguage\":\"nl\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/\",\"url\":\"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/\",\"name\":\"New collaboration with Stanley Ollivier! &ndash; Hiros\",\"isPartOf\":{\"@id\":\"https:\/\/hiros.be\/en\/#website\"},\"datePublished\":\"2023-10-06T17:35:28+00:00\",\"dateModified\":\"2023-10-06T17:39:34+00:00\",\"inLanguage\":\"nl\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hiros.be\/en\/#website\",\"url\":\"https:\/\/hiros.be\/en\/\",\"name\":\"Hiros\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/hiros.be\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hiros.be\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hiros.be\/en\/#organization\",\"name\":\"Hiros\",\"url\":\"https:\/\/hiros.be\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl\",\"@id\":\"https:\/\/hiros.be\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hiros.be\/wp-content\/uploads\/2021\/07\/Hiros_logo-1.svg\",\"contentUrl\":\"https:\/\/hiros.be\/wp-content\/uploads\/2021\/07\/Hiros_logo-1.svg\",\"caption\":\"Hiros\"},\"image\":{\"@id\":\"https:\/\/hiros.be\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/hiros.be\/en\/#\/schema\/person\/1d5315e21e564e12c8e0f36c0cd52ee4\",\"name\":\"Dagmar Teurelincx\",\"url\":\"https:\/\/hiros.be\/nl\/author\/dagmarhiros-be\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New collaboration with Stanley Ollivier! &ndash; Hiros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/","og_locale":"nl_NL","og_type":"article","og_title":"New collaboration with Stanley Ollivier! &ndash; Hiros","og_description":"06.10.2023 \u2013 Hiros is meer dan enthousiast om het nieuws te delen dat we een","og_url":"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/","og_site_name":"Hiros","article_published_time":"2023-10-06T17:35:28+00:00","article_modified_time":"2023-10-06T17:39:34+00:00","og_image":[{"width":2560,"height":2236,"url":"https:\/\/hiros.be\/wp-content\/uploads\/2023\/10\/cropped-horizontal-DC_portrait-Ollivier-Stanley_high_46-scaled.jpg","type":"image\/jpeg"}],"author":"Dagmar Teurelincx","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Dagmar Teurelincx","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/#article","isPartOf":{"@id":"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/"},"author":{"name":"Dagmar Teurelincx","@id":"https:\/\/hiros.be\/en\/#\/schema\/person\/1d5315e21e564e12c8e0f36c0cd52ee4"},"headline":"New collaboration with Stanley Ollivier!","datePublished":"2023-10-06T17:35:28+00:00","dateModified":"2023-10-06T17:39:34+00:00","mainEntityOfPage":{"@id":"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/"},"wordCount":92,"publisher":{"@id":"https:\/\/hiros.be\/en\/#organization"},"articleSection":["New collaboration"],"inLanguage":"nl"},{"@type":"WebPage","@id":"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/","url":"https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/","name":"New collaboration with Stanley Ollivier! &ndash; Hiros","isPartOf":{"@id":"https:\/\/hiros.be\/en\/#website"},"datePublished":"2023-10-06T17:35:28+00:00","dateModified":"2023-10-06T17:39:34+00:00","inLanguage":"nl","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hiros.be\/nl\/new-collaboration-with-stanley-ollivier\/"]}]},{"@type":"WebSite","@id":"https:\/\/hiros.be\/en\/#website","url":"https:\/\/hiros.be\/en\/","name":"Hiros","description":"","publisher":{"@id":"https:\/\/hiros.be\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hiros.be\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl"},{"@type":"Organization","@id":"https:\/\/hiros.be\/en\/#organization","name":"Hiros","url":"https:\/\/hiros.be\/en\/","logo":{"@type":"ImageObject","inLanguage":"nl","@id":"https:\/\/hiros.be\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hiros.be\/wp-content\/uploads\/2021\/07\/Hiros_logo-1.svg","contentUrl":"https:\/\/hiros.be\/wp-content\/uploads\/2021\/07\/Hiros_logo-1.svg","caption":"Hiros"},"image":{"@id":"https:\/\/hiros.be\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hiros.be\/en\/#\/schema\/person\/1d5315e21e564e12c8e0f36c0cd52ee4","name":"Dagmar Teurelincx","url":"https:\/\/hiros.be\/nl\/author\/dagmarhiros-be\/"}]}},"_links":{"self":[{"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/posts\/11248"}],"collection":[{"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/comments?post=11248"}],"version-history":[{"count":3,"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/posts\/11248\/revisions"}],"predecessor-version":[{"id":11255,"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/posts\/11248\/revisions\/11255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/media\/11244"}],"wp:attachment":[{"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/media?parent=11248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/categories?post=11248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hiros.be\/nl\/wp-json\/wp\/v2\/tags?post=11248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}